{"id":2622,"date":"2014-09-26T09:19:01","date_gmt":"2014-09-26T07:19:01","guid":{"rendered":"http:\/\/www.pyrgoshouse.com\/?p=2622"},"modified":"2014-09-26T09:19:01","modified_gmt":"2014-09-26T07:19:01","slug":"kafeneion-van-kalamos","status":"publish","type":"post","link":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/","title":{"rendered":"The kafeneion in Kalamos"},"content":{"rendered":"<p>Jeden Donnerstag, zum Abschluss der Kapsali Cave Tour, trinke ich zusammen mit den Teilnehmern Kaffee in der alten Dorfkneipe von Kalamos. Dieses kafenion des Ehepaars Kalligeros liegt halb versteckt am kleinen Dorfplatz. Da gibt\u2019s kein Wirtshausschild, da stehen keine Tischchen draussen, die T\u00fcr ist nicht immer offen. Viele Wanderer gehen deshalb daran vorbei. Und das ist nun wirklich schade. Denn sobald man \u00fcber die Schwelle tritt, macht man einen Schritt in die Vergangenheit. Keine Musik und keinen Fernseher. An der Wand steht noch die alte Vitrine, wo fr\u00fcher die Lebensmittel ausgestellt wurden. Eine nicht auf Hochglanz polierte kupferne Waagschale macht das Bild komplett. Erwarten Sie keinen luxuri\u00f6sen Kaffee wie Espresso oder Capuccino. Der frapp\u00e9 wird von Hand gesch\u00fcttelt, der griechische Kaffee ist altmodisch w\u00fcrzig. Und wenn wir aufbrechen, w\u00fcnscht uns Frau Kalligeros immer: kalo dromo &#8230; eine gute Wanderung.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Jeden Donnerstag, zum Abschluss der Kapsali Cave Tour, trinke ich zusammen mit den Teilnehmern Kaffee in der alten Dorfkneipe von Kalamos. Dieses kafenion des Ehepaars Kalligeros liegt halb versteckt am kleinen Dorfplatz. Da gibt\u2019s kein Wirtshausschild, da stehen keine Tischchen draussen, die T\u00fcr ist nicht immer offen. Viele Wanderer gehen<a href=\"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/\">[&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2622","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The kafeneion in Kalamos - Pyrgos House - Kythira Greece<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The kafeneion in Kalamos - Pyrgos House - Kythira Greece\" \/>\n<meta property=\"og:description\" content=\"Jeden Donnerstag, zum Abschluss der Kapsali Cave Tour, trinke ich zusammen mit den Teilnehmern Kaffee in der alten Dorfkneipe von Kalamos. Dieses kafenion des Ehepaars Kalligeros liegt halb versteckt am kleinen Dorfplatz. Da gibt\u2019s kein Wirtshausschild, da stehen keine Tischchen draussen, die T\u00fcr ist nicht immer offen. Viele Wanderer gehen[...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/\" \/>\n<meta property=\"og:site_name\" content=\"Pyrgos House - Kythira Greece\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pyrgoshouse\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-26T07:19:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2017\/01\/master-fb.jpg?fit=960%2C591&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"591\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pyrgos House\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pyrgoshouse\" \/>\n<meta name=\"twitter:site\" content=\"@pyrgoshouse\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pyrgos House\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/\"},\"author\":{\"name\":\"Pyrgos House\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/el\\\/#\\\/schema\\\/person\\\/b933d97ec49aa4df12a6cb67e9e7c365\"},\"headline\":\"The kafeneion in Kalamos\",\"datePublished\":\"2014-09-26T07:19:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/\"},\"wordCount\":452,\"commentCount\":0,\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/\",\"url\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/\",\"name\":\"The kafeneion in Kalamos - Pyrgos House - Kythira Greece\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/#website\"},\"datePublished\":\"2014-09-26T07:19:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/el\\\/#\\\/schema\\\/person\\\/b933d97ec49aa4df12a6cb67e9e7c365\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/kafeneion-van-kalamos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The kafeneion in Kalamos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/\",\"name\":\"Pyrgos House - Kythira Greece\",\"description\":\"Kythera Greece\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/el\\\/#\\\/schema\\\/person\\\/b933d97ec49aa4df12a6cb67e9e7c365\",\"name\":\"Pyrgos House\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g\",\"caption\":\"Pyrgos House\"},\"sameAs\":[\"http:\\\/\\\/pyrgoshouse.com\"],\"url\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/author\\\/pyrguss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The kafeneion in Kalamos - Pyrgos House - Kythira Greece","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/","og_locale":"de_DE","og_type":"article","og_title":"The kafeneion in Kalamos - Pyrgos House - Kythira Greece","og_description":"Jeden Donnerstag, zum Abschluss der Kapsali Cave Tour, trinke ich zusammen mit den Teilnehmern Kaffee in der alten Dorfkneipe von Kalamos. Dieses kafenion des Ehepaars Kalligeros liegt halb versteckt am kleinen Dorfplatz. Da gibt\u2019s kein Wirtshausschild, da stehen keine Tischchen draussen, die T\u00fcr ist nicht immer offen. Viele Wanderer gehen[...]","og_url":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/","og_site_name":"Pyrgos House - Kythira Greece","article_publisher":"https:\/\/www.facebook.com\/pyrgoshouse\/","article_published_time":"2014-09-26T07:19:01+00:00","og_image":[{"width":960,"height":591,"url":"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2017\/01\/master-fb.jpg?fit=960%2C591&ssl=1","type":"image\/jpeg"}],"author":"Pyrgos House","twitter_card":"summary_large_image","twitter_creator":"@pyrgoshouse","twitter_site":"@pyrgoshouse","twitter_misc":{"Verfasst von":"Pyrgos House","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/#article","isPartOf":{"@id":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/"},"author":{"name":"Pyrgos House","@id":"https:\/\/pyrgoshouse.com\/el\/#\/schema\/person\/b933d97ec49aa4df12a6cb67e9e7c365"},"headline":"The kafeneion in Kalamos","datePublished":"2014-09-26T07:19:01+00:00","mainEntityOfPage":{"@id":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/"},"wordCount":452,"commentCount":0,"articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/","url":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/","name":"The kafeneion in Kalamos - Pyrgos House - Kythira Greece","isPartOf":{"@id":"https:\/\/pyrgoshouse.com\/de\/#website"},"datePublished":"2014-09-26T07:19:01+00:00","author":{"@id":"https:\/\/pyrgoshouse.com\/el\/#\/schema\/person\/b933d97ec49aa4df12a6cb67e9e7c365"},"breadcrumb":{"@id":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pyrgoshouse.com\/de\/kafeneion-van-kalamos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pyrgoshouse.com\/de\/"},{"@type":"ListItem","position":2,"name":"The kafeneion in Kalamos"}]},{"@type":"WebSite","@id":"https:\/\/pyrgoshouse.com\/de\/#website","url":"https:\/\/pyrgoshouse.com\/de\/","name":"Pyrgos House - Kythira Greece","description":"Kythera Greece","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pyrgoshouse.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/pyrgoshouse.com\/el\/#\/schema\/person\/b933d97ec49aa4df12a6cb67e9e7c365","name":"Pyrgos House","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g","caption":"Pyrgos House"},"sameAs":["http:\/\/pyrgoshouse.com"],"url":"https:\/\/pyrgoshouse.com\/de\/author\/pyrguss\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/posts\/2622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/comments?post=2622"}],"version-history":[{"count":0,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/posts\/2622\/revisions"}],"wp:attachment":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/media?parent=2622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/categories?post=2622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/tags?post=2622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}