{"id":6186,"date":"2019-05-04T17:09:36","date_gmt":"2019-05-04T15:09:36","guid":{"rendered":"https:\/\/pyrgoshouse.com\/?p=6186"},"modified":"2019-05-04T17:09:36","modified_gmt":"2019-05-04T15:09:36","slug":"our-successful-cooking-workshop-starts-again","status":"publish","type":"post","link":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/","title":{"rendered":"Unser erfolgreicher Koch-Workshop beginnt wieder"},"content":{"rendered":"<p>Ab der zweiten Maiwoche kann man wieder an unserem Koch-Workshop teilnehmen. Dabei weiht Sie Chrysoula in die Geheimnisse der griechischen K\u00fcche ein. Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen und Gewohnheiten und vom t\u00e4glichen Leben. Danach heisst es nat\u00fcrlich: den herrlichen Lunch mit einem (oder zwei ..) Glas Wein auf der Veranda geniessen.<br \/>\nDer Workshop findet einmal w\u00f6chentlich statt, die Gruppen sind klein (maximal 6 Personen). Reservieren k\u00f6nnen Sie diese unvergessliche Erfahrung via info@pyrgoshouse.com.<br \/>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Ab der zweiten Maiwoche kann man wieder an unserem Koch-Workshop teilnehmen. Dabei weiht Sie Chrysoula in die Geheimnisse der griechischen K\u00fcche ein. Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen<a href=\"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/\">[&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":6187,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Unser erfolgreicher Koch-Workshop beginnt wieder","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-6186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unser erfolgreicher Koch-Workshop beginnt wieder - Pyrgos House - Kythira Greece<\/title>\n<meta name=\"description\" content=\"Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen und Gewohnheiten und vom t\u00e4glichen Leben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unser erfolgreicher Koch-Workshop beginnt wieder - Pyrgos House - Kythira Greece\" \/>\n<meta property=\"og:description\" content=\"Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen und Gewohnheiten und vom t\u00e4glichen Leben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/\" \/>\n<meta property=\"og:site_name\" content=\"Pyrgos House - Kythira Greece\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pyrgoshouse\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-04T15:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2019\/05\/DSC01046.jpg?fit=1024%2C768&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pyrgos House\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pyrgoshouse\" \/>\n<meta name=\"twitter:site\" content=\"@pyrgoshouse\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pyrgos House\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/\"},\"author\":{\"name\":\"Pyrgos House\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/el\\\/#\\\/schema\\\/person\\\/b933d97ec49aa4df12a6cb67e9e7c365\"},\"headline\":\"Unser erfolgreicher Koch-Workshop beginnt wieder\",\"datePublished\":\"2019-05-04T15:09:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/\"},\"wordCount\":340,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/pyrgoshouse.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/DSC01046.jpg?fit=1024%2C768&ssl=1\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/\",\"url\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/\",\"name\":\"Unser erfolgreicher Koch-Workshop beginnt wieder - Pyrgos House - Kythira Greece\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/pyrgoshouse.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/DSC01046.jpg?fit=1024%2C768&ssl=1\",\"datePublished\":\"2019-05-04T15:09:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/el\\\/#\\\/schema\\\/person\\\/b933d97ec49aa4df12a6cb67e9e7c365\"},\"description\":\"Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen und Gewohnheiten und vom t\u00e4glichen Leben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/pyrgoshouse.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/DSC01046.jpg?fit=1024%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/pyrgoshouse.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/DSC01046.jpg?fit=1024%2C768&ssl=1\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/our-successful-cooking-workshop-starts-again\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser erfolgreicher Koch-Workshop beginnt wieder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/\",\"name\":\"Pyrgos House - Kythira Greece\",\"description\":\"Kythera Greece\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pyrgoshouse.com\\\/el\\\/#\\\/schema\\\/person\\\/b933d97ec49aa4df12a6cb67e9e7c365\",\"name\":\"Pyrgos House\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g\",\"caption\":\"Pyrgos House\"},\"sameAs\":[\"http:\\\/\\\/pyrgoshouse.com\"],\"url\":\"https:\\\/\\\/pyrgoshouse.com\\\/de\\\/author\\\/pyrguss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unser erfolgreicher Koch-Workshop beginnt wieder - Pyrgos House - Kythira Greece","description":"Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen und Gewohnheiten und vom t\u00e4glichen Leben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/","og_locale":"de_DE","og_type":"article","og_title":"Unser erfolgreicher Koch-Workshop beginnt wieder - Pyrgos House - Kythira Greece","og_description":"Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen und Gewohnheiten und vom t\u00e4glichen Leben.","og_url":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/","og_site_name":"Pyrgos House - Kythira Greece","article_publisher":"https:\/\/www.facebook.com\/pyrgoshouse\/","article_published_time":"2019-05-04T15:09:36+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2019\/05\/DSC01046.jpg?fit=1024%2C768&ssl=1","type":"image\/jpeg"}],"author":"Pyrgos House","twitter_card":"summary_large_image","twitter_creator":"@pyrgoshouse","twitter_site":"@pyrgoshouse","twitter_misc":{"Verfasst von":"Pyrgos House","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#article","isPartOf":{"@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/"},"author":{"name":"Pyrgos House","@id":"https:\/\/pyrgoshouse.com\/el\/#\/schema\/person\/b933d97ec49aa4df12a6cb67e9e7c365"},"headline":"Unser erfolgreicher Koch-Workshop beginnt wieder","datePublished":"2019-05-04T15:09:36+00:00","mainEntityOfPage":{"@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/"},"wordCount":340,"commentCount":0,"image":{"@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2019\/05\/DSC01046.jpg?fit=1024%2C768&ssl=1","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/","url":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/","name":"Unser erfolgreicher Koch-Workshop beginnt wieder - Pyrgos House - Kythira Greece","isPartOf":{"@id":"https:\/\/pyrgoshouse.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#primaryimage"},"image":{"@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2019\/05\/DSC01046.jpg?fit=1024%2C768&ssl=1","datePublished":"2019-05-04T15:09:36+00:00","author":{"@id":"https:\/\/pyrgoshouse.com\/el\/#\/schema\/person\/b933d97ec49aa4df12a6cb67e9e7c365"},"description":"Sie kochen mit Gem\u00fcse und Kr\u00e4utern, die Chrysoula am selben Morgen in ihrem Garten geerntet hat, frisch und biologisch. W\u00e4hrend des Kochens erz\u00e4hlt Ihnen Chrysoula von kytherianischen Traditionen und Gewohnheiten und vom t\u00e4glichen Leben.","breadcrumb":{"@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/"]]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#primaryimage","url":"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2019\/05\/DSC01046.jpg?fit=1024%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2019\/05\/DSC01046.jpg?fit=1024%2C768&ssl=1","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/pyrgoshouse.com\/de\/our-successful-cooking-workshop-starts-again\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pyrgoshouse.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unser erfolgreicher Koch-Workshop beginnt wieder"}]},{"@type":"WebSite","@id":"https:\/\/pyrgoshouse.com\/de\/#website","url":"https:\/\/pyrgoshouse.com\/de\/","name":"Pyrgos House - Kythira Greece","description":"Kythera Greece","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pyrgoshouse.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/pyrgoshouse.com\/el\/#\/schema\/person\/b933d97ec49aa4df12a6cb67e9e7c365","name":"Pyrgos House","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b0f46766dbffc36cce68962b4cf712bf2db8b8edf816c80c06b2e4ac13501d8?s=96&d=mm&r=g","caption":"Pyrgos House"},"sameAs":["http:\/\/pyrgoshouse.com"],"url":"https:\/\/pyrgoshouse.com\/de\/author\/pyrguss\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/pyrgoshouse.com\/wp-content\/uploads\/2019\/05\/DSC01046.jpg?fit=1024%2C768&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/posts\/6186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/comments?post=6186"}],"version-history":[{"count":2,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/posts\/6186\/revisions"}],"predecessor-version":[{"id":6191,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/posts\/6186\/revisions\/6191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/media\/6187"}],"wp:attachment":[{"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/media?parent=6186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/categories?post=6186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pyrgoshouse.com\/de\/wp-json\/wp\/v2\/tags?post=6186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}